{"id":370,"date":"2026-04-29T09:37:48","date_gmt":"2026-04-29T09:37:48","guid":{"rendered":"https:\/\/herrin-eve-sm.com\/?page_id=370"},"modified":"2026-08-12T16:04:55","modified_gmt":"2026-08-12T16:04:55","slug":"sklaven-ausbildung","status":"publish","type":"page","link":"https:\/\/herrin-eve-sm.com\/index.php\/sklaven-ausbildung\/","title":{"rendered":"SKLAVEN-AUSBILDUNG"},"content":{"rendered":"\n  \n    \n    <section class=\"u-clearfix u-image u-section-2\" id=\"block-1\" data-image-width=\"1688\" data-image-height=\"1124\" style=\"background-image: url(&quot;https:\/\/herrin-eve-sm.com\/wp-content\/uploads\/2026\/05\/Kerker3.jpeg&quot;);\">\n      <div class=\"u-clearfix u-sheet u-sheet-1\">\n        <h1 class=\"u-custom-font u-text u-text-body-alt-color u-text-default u-text-1\">SKLAVEN-AUSBILDUNG<\/h1>\n        <h3 class=\"u-align-center u-custom-font u-text u-text-body-alt-color u-text-2\"> MANCHE MENSCHEN SUCHEN ENTSPANNUNG.&nbsp;<br>MANCHE MENSCHEN\n  SUCHEN DIE HERAUSFORDERUNG IHRER GRENZEN.&nbsp;<br>MANCHE MENSCHEN\n  SUCHEN MACHT.&nbsp;<br>ALLE, DIE MEIN STUDIO BETRETEN, SUCHEN ETWAS, NUR HOFFENTLICH\n  KEINEN ORT DES KOMFORTS. ES GEHT HIER NICHT UM BEQUEMLICHKEIT, SONDERN UM\n  KONTROLLE, DISZIPLIN, KONSEQUENZ. \n        <\/h3>\n        <img decoding=\"async\" class=\"u-border-5 u-border-grey-40 u-image u-image-default u-image-1\" src=\"https:\/\/herrin-eve-sm.com\/wp-content\/uploads\/2026\/06\/1-1.jpeg\" alt=\"\" data-image-width=\"1600\" data-image-height=\"1066\">\n        <div class=\"u-expanded-width u-gallery u-layout-grid u-lightbox u-no-transition u-show-text-none u-gallery-1\">\n          <div class=\"u-gallery-inner u-gallery-inner-1\">\n            <div class=\"u-border-5 u-border-grey-40 u-effect-hover-zoom u-gallery-item u-gallery-item-1\">\n              <div class=\"u-back-slide\" data-image-width=\"1295\" data-image-height=\"1600\">\n                <img decoding=\"async\" class=\"u-back-image u-expanded\" src=\"https:\/\/herrin-eve-sm.com\/wp-content\/uploads\/2026\/06\/2-1.jpeg\">\n              <\/div>\n              <div class=\"u-over-slide u-shading u-over-slide-1\"><\/div>\n            <\/div>\n            <div class=\"u-border-5 u-border-grey-40 u-effect-hover-zoom u-gallery-item u-gallery-item-2\">\n              <div class=\"u-back-slide\" data-image-width=\"1066\" data-image-height=\"1600\">\n                <img decoding=\"async\" class=\"u-back-image u-expanded\" src=\"https:\/\/herrin-eve-sm.com\/wp-content\/uploads\/2026\/06\/3-1.jpeg\">\n              <\/div>\n              <div class=\"u-over-slide u-shading u-over-slide-2\"><\/div>\n            <\/div>\n            <div class=\"u-border-5 u-border-grey-40 u-effect-hover-zoom u-gallery-item u-gallery-item-3\">\n              <div class=\"u-back-slide\" data-image-width=\"3024\" data-image-height=\"4032\">\n                <img decoding=\"async\" class=\"u-back-image u-expanded\" src=\"https:\/\/herrin-eve-sm.com\/wp-content\/uploads\/2026\/08\/8-scaled.jpg\">\n              <\/div>\n              <div class=\"u-over-slide u-shading u-over-slide-3\"><\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n        <div class=\"u-expanded-width u-gallery u-layout-grid u-lightbox u-no-transition u-show-text-none u-gallery-2\">\n          <div class=\"u-gallery-inner u-gallery-inner-2\">\n            <div class=\"u-border-5 u-border-grey-40 u-effect-hover-zoom u-gallery-item u-gallery-item-4\">\n              <div class=\"u-back-slide\" data-image-width=\"1066\" data-image-height=\"1600\">\n                <img decoding=\"async\" class=\"u-back-image u-expanded\" src=\"https:\/\/herrin-eve-sm.com\/wp-content\/uploads\/2026\/06\/4-1.jpeg\">\n              <\/div>\n              <div class=\"u-over-slide u-shading u-over-slide-4\"><\/div>\n            <\/div>\n            <div class=\"u-border-5 u-border-grey-40 u-effect-hover-zoom u-gallery-item u-gallery-item-5\">\n              <div class=\"u-back-slide\" data-image-width=\"1066\" data-image-height=\"1600\">\n                <img decoding=\"async\" class=\"u-back-image u-expanded\" src=\"https:\/\/herrin-eve-sm.com\/wp-content\/uploads\/2026\/06\/5-1.jpeg\">\n              <\/div>\n              <div class=\"u-over-slide u-shading u-over-slide-5\"><\/div>\n            <\/div>\n            <div class=\"u-border-5 u-border-grey-40 u-effect-hover-zoom u-gallery-item u-gallery-item-6\">\n              <div class=\"u-back-slide\" data-image-width=\"1200\" data-image-height=\"1600\">\n                <img decoding=\"async\" class=\"u-back-image u-expanded\" src=\"https:\/\/herrin-eve-sm.com\/wp-content\/uploads\/2026\/06\/6-1.jpeg\">\n              <\/div>\n              <div class=\"u-over-slide u-shading u-over-slide-6\"><\/div>\n            <\/div>\n            <div class=\"u-border-5 u-border-grey-40 u-effect-hover-zoom u-gallery-item u-gallery-item-7\">\n              <div class=\"u-back-slide\" data-image-width=\"1000\" data-image-height=\"1500\">\n                <img decoding=\"async\" class=\"u-back-image u-expanded\" src=\"https:\/\/herrin-eve-sm.com\/wp-content\/uploads\/2026\/06\/7-1.jpeg\">\n              <\/div>\n              <div class=\"u-over-slide u-shading u-over-slide-7\"><\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n        <div class=\"custom-expanded u-gallery u-layout-grid u-lightbox u-no-transition u-show-text-none u-gallery-3\">\n          <div class=\"u-gallery-inner u-gallery-inner-3\">\n            <div class=\"u-border-5 u-border-grey-25 u-effect-hover-zoom u-gallery-item u-gallery-item-8\">\n              <div class=\"u-back-slide\" data-image-width=\"1330\" data-image-height=\"2212\">\n                <img decoding=\"async\" class=\"u-back-image u-expanded\" src=\"https:\/\/herrin-eve-sm.com\/wp-content\/uploads\/2026\/08\/18-1.jpg\">\n              <\/div>\n              <div class=\"u-over-slide u-shading u-over-slide-8\"><\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n        <p class=\"u-align-left u-custom-font u-text u-text-body-alt-color u-text-3\"> Ich \u00f6ffne die T\u00fcr zu meinem Studio: \"Geh hinein!\". Er tritt ein und sieht sich um. Das Studio ist vielf\u00e4ltig eingerichtet\u2026und sehr sauber und geordnet. Jeder Gegenstand hat seinen Platz. <br>\n          <br>\u201eDu m\u00f6chtest als Sklave ausgebildet werden?\u201c <br>\n          <br>\u201eJa\u201c, antwortet er leise. <br>\n          <br>\"Knie dich dort hin!\". Ich zeige auf eine sehr unbequeme Matte und mustere ihn schweigend. Die Stille macht ihn zunehmend unsicher. Ich sage schlie\u00dflich: \"Deine erste Lektion beginnt jetzt: Nicht bewegen, Warten, Zuh\u00f6ren.\u201c <br>Er ist ganz ruhig, aber auch die kleinste Bewegung, jeder nerv\u00f6se Blick entgeht mir nicht. Er wartet auf weitere Anweisungen. <br>\u201eDu glaubst vermutlich, Ausbildung bedeutet nur H\u00e4rte und Strenge\u201c, sage ich. Er nickt. <br>Ich fahre bestimmend fort: \"Stimmt. Aber mindestens genauso wichtig sind Geduld und Disziplin, um absuluten Gehorsam deiner Herrin gege\u00fcber zu begreifen und zu leben. Deshalb musst du physische Schmeizen und psychische Leiden ertragen wollen\u201c. Stille\u2026 \"Ist dir das klar, worauf du dich bei mir einl\u00e4sst? Ich will einen sehr guten Sklaven hier haben!\" <br>\u201eJa, Herrin.\u201c <br>\n          <br>Ein leichtes L\u00e4cheln erscheint auf meinen Lippen. <br>\n          <br>\"Dann war das deine erste Lektion. Deine Ausbildung hat begonnen.\" <br>Als er das Studio verl\u00e4sst, verbeugt er sich respektvoll und nur ich weiss: Beim n\u00e4chsten Besuch w\u00fcrde die eigentliche Herausforderung beginnen!\n        <\/p>\n      <\/div>\n    <\/section>\n    <section class=\"u-align-center u-clearfix u-container-align-center u-section-3\" id=\"block-3\">\n      <div class=\"u-clearfix u-sheet u-valign-middle u-sheet-1\">\n        <div class=\"u-expanded-width u-gallery u-layout-grid u-lightbox u-no-transition u-show-text-none u-gallery-1\">\n          <div class=\"u-gallery-inner u-gallery-inner-1\">\n            <div class=\"u-border-5 u-border-grey-40 u-effect-hover-zoom u-gallery-item u-gallery-item-1\">\n              <div class=\"u-back-slide\" data-image-width=\"1600\" data-image-height=\"1066\">\n                <img decoding=\"async\" class=\"u-back-image u-expanded\" src=\"https:\/\/herrin-eve-sm.com\/wp-content\/uploads\/2026\/06\/9-1.jpeg\">\n              <\/div>\n              <div class=\"u-over-slide u-shading u-over-slide-1\"><\/div>\n            <\/div>\n            <div class=\"u-border-5 u-border-grey-40 u-effect-hover-zoom u-gallery-item u-gallery-item-2\">\n              <div class=\"u-back-slide\" data-image-width=\"1600\" data-image-height=\"1066\">\n                <img decoding=\"async\" class=\"u-back-image u-expanded\" src=\"https:\/\/herrin-eve-sm.com\/wp-content\/uploads\/2026\/06\/10-1.jpeg\">\n              <\/div>\n              <div class=\"u-over-slide u-shading u-over-slide-2\"><\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/section>\n    <section class=\"u-align-center u-clearfix u-container-align-center u-section-4\" id=\"block-5\">\n      <div class=\"u-clearfix u-sheet u-valign-middle-lg u-valign-middle-md u-valign-middle-sm u-valign-middle-xs u-sheet-1\">\n        <div class=\"u-expanded-width u-gallery u-layout-grid u-lightbox u-no-transition u-show-text-none u-gallery-1\">\n          <div class=\"u-gallery-inner u-gallery-inner-1\">\n            <div class=\"u-border-5 u-border-grey-40 u-effect-hover-zoom u-gallery-item u-gallery-item-1\">\n              <div class=\"u-back-slide\" data-image-width=\"1066\" data-image-height=\"1600\">\n                <img decoding=\"async\" class=\"u-back-image u-expanded\" src=\"https:\/\/herrin-eve-sm.com\/wp-content\/uploads\/2026\/06\/11-1.jpeg\">\n              <\/div>\n              <div class=\"u-over-slide u-shading u-over-slide-1\"><\/div>\n            <\/div>\n            <div class=\"u-border-5 u-border-grey-40 u-effect-hover-zoom u-gallery-item u-gallery-item-2\">\n              <div class=\"u-back-slide\" data-image-width=\"1200\" data-image-height=\"1600\">\n                <img decoding=\"async\" class=\"u-back-image u-expanded\" src=\"https:\/\/herrin-eve-sm.com\/wp-content\/uploads\/2026\/06\/12-1.jpeg\">\n              <\/div>\n              <div class=\"u-over-slide u-shading u-over-slide-2\"><\/div>\n            <\/div>\n            <div class=\"u-border-5 u-border-grey-40 u-effect-hover-zoom u-gallery-item u-gallery-item-3\">\n              <div class=\"u-back-slide\" data-image-width=\"901\" data-image-height=\"1600\">\n                <img decoding=\"async\" class=\"u-back-image u-expanded\" src=\"https:\/\/herrin-eve-sm.com\/wp-content\/uploads\/2026\/06\/13-1.jpeg\">\n              <\/div>\n              <div class=\"u-over-slide u-shading u-over-slide-3\"><\/div>\n            <\/div>\n            <div class=\"u-border-5 u-border-grey-40 u-effect-hover-zoom u-gallery-item u-gallery-item-4\">\n              <div class=\"u-back-slide\" data-image-width=\"1090\" data-image-height=\"1600\">\n                <img decoding=\"async\" class=\"u-back-image u-expanded\" src=\"https:\/\/herrin-eve-sm.com\/wp-content\/uploads\/2026\/06\/14-1.jpeg\">\n              <\/div>\n              <div class=\"u-over-slide u-shading u-over-slide-4\"><\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n        <div class=\"custom-expanded u-gallery u-layout-grid u-lightbox u-no-transition u-show-text-none u-gallery-2\">\n          <div class=\"u-gallery-inner u-gallery-inner-2\">\n            <div class=\"u-border-5 u-border-grey-40 u-effect-hover-zoom u-gallery-item u-gallery-item-5\">\n              <div class=\"u-back-slide\" data-image-width=\"1066\" data-image-height=\"1600\">\n                <img decoding=\"async\" class=\"u-back-image u-expanded\" src=\"https:\/\/herrin-eve-sm.com\/wp-content\/uploads\/2026\/06\/15-1.jpeg\">\n              <\/div>\n              <div class=\"u-over-slide u-shading u-over-slide-5\"><\/div>\n            <\/div>\n            <div class=\"u-border-5 u-border-grey-40 u-effect-hover-zoom u-gallery-item u-gallery-item-6\">\n              <div class=\"u-back-slide\" data-image-width=\"1200\" data-image-height=\"1600\">\n                <img decoding=\"async\" class=\"u-back-image u-expanded\" src=\"https:\/\/herrin-eve-sm.com\/wp-content\/uploads\/2026\/06\/16.jpeg\">\n              <\/div>\n              <div class=\"u-over-slide u-shading u-over-slide-6\"><\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/section>\n    \n    \n    \n  \n","protected":false},"excerpt":{"rendered":"<p>SKLAVEN-AUSBILDUNG MANCHE MENSCHEN SUCHEN ENTSPANNUNG.&nbsp;MANCHE MENSCHEN SUCHEN DIE HERAUSFORDERUNG IHRER GRENZEN.&nbsp;MANCHE MENSCHEN SUCHEN MACHT.&nbsp;ALLE, DIE MEIN STUDIO BETRETEN, SUCHEN ETWAS, NUR HOFFENTLICH KEINEN ORT DES KOMFORTS. ES GEHT HIER NICHT UM BEQUEMLICHKEIT, SONDERN UM KONTROLLE, DISZIPLIN, KONSEQUENZ. Ich \u00f6ffne die T\u00fcr zu meinem Studio: &#8222;Geh hinein!&#8220;. Er tritt ein und sieht sich um. Das Studio &hellip; <a href=\"https:\/\/herrin-eve-sm.com\/index.php\/sklaven-ausbildung\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8222;SKLAVEN-AUSBILDUNG&#8220;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-370","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/herrin-eve-sm.com\/index.php\/wp-json\/wp\/v2\/pages\/370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/herrin-eve-sm.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/herrin-eve-sm.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/herrin-eve-sm.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/herrin-eve-sm.com\/index.php\/wp-json\/wp\/v2\/comments?post=370"}],"version-history":[{"count":12,"href":"https:\/\/herrin-eve-sm.com\/index.php\/wp-json\/wp\/v2\/pages\/370\/revisions"}],"predecessor-version":[{"id":2114,"href":"https:\/\/herrin-eve-sm.com\/index.php\/wp-json\/wp\/v2\/pages\/370\/revisions\/2114"}],"wp:attachment":[{"href":"https:\/\/herrin-eve-sm.com\/index.php\/wp-json\/wp\/v2\/media?parent=370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}